{"id":2228,"date":"2019-04-08T17:28:12","date_gmt":"2019-04-08T15:28:12","guid":{"rendered":"http:\/\/wienerschlegel.at\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/"},"modified":"2025-03-22T14:08:20","modified_gmt":"2025-03-22T13:08:20","slug":"orchestra-whip-set-1-4-with-wooden-handle","status":"publish","type":"product","link":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/","title":{"rendered":"Orchestra whip set 1-4 with wooden handle"},"content":{"rendered":"<p>orchestra whip set 1-4 with wooden handle<\/p>\n<ul>\n<li><span lang=\"en\" style=\"color: #333333; font-size: 14.4px;\">material: ash wood<\/span><\/li>\n<li><span lang=\"en\" style=\"color: #333333; font-size: 14.4px;\">material thickness: 20mm<\/span><\/li>\n<li><span style=\"color: #333333; font-size: 14.4px;\">whip 1: 500 x 100mm<\/span><\/li>\n<li>whip 2: 450 x 75mm<\/li>\n<li>whip 3: 400 x 50mm<\/li>\n<li>whip 4: 330x 50mm<\/li>\n<li>with wooden handle<\/li>\n<li>oiled twice with ecological Swedish linseed oil<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Orchestra whip set 1-4 with wooden handle<\/p>\n","protected":false},"featured_media":1536,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[117,118],"product_tag":[],"class_list":{"0":"post-2228","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-whip","7":"product_cat-whip-with-wood-handle","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orchestra whip set 1-4 with wooden handle - Wienerschlegel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orchestra whip set 1-4 with wooden handle - Wienerschlegel\" \/>\n<meta property=\"og:description\" content=\"Orchestra whip set 1-4 with wooden handle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/\" \/>\n<meta property=\"og:site_name\" content=\"Wienerschlegel\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-22T13:08:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wienerschlegel.at\/wp-content\/uploads\/2019\/04\/Gruppe-1-1000-x-1000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/\",\"url\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/\",\"name\":\"Orchestra whip set 1-4 with wooden handle - Wienerschlegel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wienerschlegel.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Gruppe-1-1000-x-1000.jpg\",\"datePublished\":\"2019-04-08T15:28:12+00:00\",\"dateModified\":\"2025-03-22T13:08:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wienerschlegel.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Gruppe-1-1000-x-1000.jpg\",\"contentUrl\":\"https:\\\/\\\/wienerschlegel.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Gruppe-1-1000-x-1000.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"OLYMPUS DIGITAL CAMERA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/produkt\\\/orchestra-whip-set-1-4-with-wooden-handle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/wienerschlegel.at\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orchestra whip set 1-4 with wooden handle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/\",\"name\":\"Wienerschlegel\",\"description\":\"Wienerschlegel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wienerschlegel.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orchestra whip set 1-4 with wooden handle - Wienerschlegel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/","og_locale":"en_US","og_type":"article","og_title":"Orchestra whip set 1-4 with wooden handle - Wienerschlegel","og_description":"Orchestra whip set 1-4 with wooden handle","og_url":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/","og_site_name":"Wienerschlegel","article_modified_time":"2025-03-22T13:08:20+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/wienerschlegel.at\/wp-content\/uploads\/2019\/04\/Gruppe-1-1000-x-1000.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/","url":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/","name":"Orchestra whip set 1-4 with wooden handle - Wienerschlegel","isPartOf":{"@id":"https:\/\/wienerschlegel.at\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/#primaryimage"},"image":{"@id":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/#primaryimage"},"thumbnailUrl":"https:\/\/wienerschlegel.at\/wp-content\/uploads\/2019\/04\/Gruppe-1-1000-x-1000.jpg","datePublished":"2019-04-08T15:28:12+00:00","dateModified":"2025-03-22T13:08:20+00:00","breadcrumb":{"@id":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/#primaryimage","url":"https:\/\/wienerschlegel.at\/wp-content\/uploads\/2019\/04\/Gruppe-1-1000-x-1000.jpg","contentUrl":"https:\/\/wienerschlegel.at\/wp-content\/uploads\/2019\/04\/Gruppe-1-1000-x-1000.jpg","width":1000,"height":1000,"caption":"OLYMPUS DIGITAL CAMERA"},{"@type":"BreadcrumbList","@id":"https:\/\/wienerschlegel.at\/en\/produkt\/orchestra-whip-set-1-4-with-wooden-handle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wienerschlegel.at\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/wienerschlegel.at\/shop\/"},{"@type":"ListItem","position":3,"name":"Orchestra whip set 1-4 with wooden handle"}]},{"@type":"WebSite","@id":"https:\/\/wienerschlegel.at\/en\/#website","url":"https:\/\/wienerschlegel.at\/en\/","name":"Wienerschlegel","description":"Wienerschlegel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wienerschlegel.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/product\/2228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/comments?post=2228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/media\/1536"}],"wp:attachment":[{"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/media?parent=2228"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/product_brand?post=2228"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/product_cat?post=2228"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wienerschlegel.at\/en\/wp-json\/wp\/v2\/product_tag?post=2228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}